{"id":17322,"date":"2022-09-01T13:03:00","date_gmt":"2022-09-01T11:03:00","guid":{"rendered":"https:\/\/test-01.bergfreunde.de\/blog\/pflegeanleitung-hardshelljacken\/"},"modified":"2025-08-08T10:33:13","modified_gmt":"2025-08-08T08:33:13","slug":"pflegeanleitung-hardshelljacken","status":"publish","type":"post","link":"https:\/\/www.bergfreunde.de\/blog\/pflegeanleitung-hardshelljacken\/","title":{"rendered":"Hardshelljacken reparieren \u2013 Erste Hilfe f\u00fcr die Jacke"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2022\/12\/Bild-61.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2022\/12\/Bild-61.jpg\" alt=\"Reparatur einer blauen Hardshelljacke\" class=\"wp-image-60442\" style=\"object-fit:cover\" srcset=\"https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2022\/12\/Bild-61.jpg 900w, https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2022\/12\/Bild-61-300x200.jpg 300w, https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2022\/12\/Bild-61-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><figcaption class=\"wp-element-caption\">Wir erkl\u00e4ren Dir, auf was Du bei der Reparatur der Hardshell achten musst<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Fr\u00fcher war alles einfacher. Loch im Wollpullover: Mutti stopft das. Hose zerrissen: Zuerst gab es \u00c4rger mit dem Vater, danach einen Flicken von der Mutter. Die Zeiten der Strickpullover und Kniebundhosen sind aber in den Bergen schon lang vorbei. Heute kommen Funktionstextilien aller Art zum Einsatz und teilweise auch an ihre Grenzen. Muss aber ein <strong>Brandloch<\/strong> oder ein <strong>Riss<\/strong> in der teuren Hardshelljacke gleich das Aus f\u00fcr dieses Kleidungsst\u00fcck bedeuten? Wie kann man sich <strong>auch unterwegs<\/strong> behelfen, und worauf sollte man beim Hardshelljacke reparieren achten?<\/p>\n\n\n\n<p>Die gute Nachricht zuerst: Brandl\u00f6cher, Risse und Schnitte bedeuten nicht automatisch das Aus f\u00fcr die geliebte Hardshelljacke. Je nach Art und Gr\u00f6\u00dfe der Besch\u00e4digung gibt es mehrere Reparaturmethoden, die auch von Laien einfach anzuwenden sind. In aller Regel wird <strong>besch\u00e4digtes Material geklebt<\/strong>. Keinesfalls sollte man also zu Nadel und Faden greifen. Durch das N\u00e4hen entst\u00fcnden zahlreiche kleine Einstichl\u00f6cher in der Membran, was sich wiederum negativ auf die Funktionalit\u00e4t des Kleidungsst\u00fccks auswirken w\u00fcrde. Bei schwerwiegenden Besch\u00e4digungen sollte man sich <strong>professionelle Hilfe<\/strong> holen.<\/p>\n\n\n\n<!--more-->\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-beschadigungen-durch-abnutzung\">Besch\u00e4digungen durch Abnutzung<\/h2>\n\n\n\n<p>Viele Besch\u00e4digungen, wie abgel\u00f6ste Verklebungen oder aufgescheuerte N\u00e4hte, entstehen durch den Gebrauch. Ist man viel mit schwerem Gep\u00e4ck unterwegs, leiden die <strong>Partien, an denen der Rucksack aufliegt<\/strong>, besonders stark. Hier kommt es nach intensivem Gebrauch meist zu Besch\u00e4digungen durch Abnutzung und Materialerm\u00fcdung.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2021\/05\/Bild-5.jpg\"><img decoding=\"async\" width=\"900\" height=\"600\" data-id=\"17323\" src=\"https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2021\/05\/Bild-5.jpg\" alt=\"Pflegeanleitung Hardshell, Aufgescheuerte N\u00e4hte\" class=\"wp-image-17323\" srcset=\"https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2021\/05\/Bild-5.jpg 900w, https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2021\/05\/Bild-5-300x200.jpg 300w, https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2021\/05\/Bild-5-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><figcaption class=\"wp-element-caption\">Aufgescheuerte Naht<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2022\/09\/Hardshell-reparieren_zerrissene-Jacke_original.jpeg\"><img decoding=\"async\" width=\"1515\" height=\"916\" data-id=\"125002\" src=\"https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2022\/09\/Hardshell-reparieren_zerrissene-Jacke_original.jpeg\" alt=\"Riss in der Jacke.\" class=\"wp-image-125002\" srcset=\"https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2022\/09\/Hardshell-reparieren_zerrissene-Jacke_original.jpeg 1515w, https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2022\/09\/Hardshell-reparieren_zerrissene-Jacke_original-300x181.jpeg 300w, https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2022\/09\/Hardshell-reparieren_zerrissene-Jacke_original-1500x907.jpeg 1500w, https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2022\/09\/Hardshell-reparieren_zerrissene-Jacke_original-768x464.jpeg 768w\" sizes=\"(max-width: 1515px) 100vw, 1515px\" \/><\/a><figcaption class=\"wp-element-caption\">Riss in der Jacke<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2021\/05\/Bild-31.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" data-id=\"17331\" src=\"https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2021\/05\/Bild-31.jpg\" alt=\"Pflegeanleitung Hardshell, Abgel\u00f6ste Verklebungen\" class=\"wp-image-17331\" srcset=\"https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2021\/05\/Bild-31.jpg 900w, https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2021\/05\/Bild-31-300x200.jpg 300w, https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2021\/05\/Bild-31-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><figcaption class=\"wp-element-caption\">Abgel\u00f6ste Verklebung<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p>Wer den Schaden jedoch fr\u00fch erkennt, kann ihn schnell und einfach selbst beheben und seine Hardshelljacke reparieren. <strong>Abgel\u00f6stes Nahtband<\/strong> l\u00e4sst sich vergleichsweise gut reparieren. Sofern das Band noch nicht in Fetzen h\u00e4ngt, kann dieses einfach wieder mit einem <strong>geeigneten Textilkleber<\/strong> fixiert werden. Nach dem Auftragen des Klebers m\u00fcssen die zu klebenden Teile zusammengedr\u00fcckt oder mittels Stein etc. beschwert werden. Ebenfalls k\u00f6nnen geringf\u00fcgig besch\u00e4digte N\u00e4hte mit <strong>einem Tropfen Urethankleber<\/strong> repariert werden. In der Regel muss der Kleber f\u00fcr <strong>12-24 Stunden aush\u00e4rten<\/strong>.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2021\/05\/Bild-41.jpg\"><img decoding=\"async\" src=\"https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2021\/05\/Bild-41.jpg\" alt=\"Pflegeanleitung Hardshell, Selbstklebendes Nahtband\" class=\"wp-image-24888\" style=\"object-fit:cover\"\/><\/a><figcaption class=\"wp-element-caption\">Selbstklebendes Nahtband<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Hat sich die Nahtabdeckung bereits in Luft aufgel\u00f6st, kann man entweder <strong>selbstklebendes Nahtband<\/strong> oder kleinere Flicken aufbringen. Wichtig: Die zu flickende Stelle muss <strong>zuvor gr\u00fcndlich gereinigt<\/strong> werden. Danach erst kann das Band oder der Flicken aufgebracht werden. Da diese in der Regel selbstklebend sind, ist die Verarbeitung vergleichsweise einfach. Jedoch sollte man darauf achten, dass <strong>keine Falten<\/strong> entstehen und der Flicken \u00fcberall fest am zu reparierenden Material klebt.<\/p>\n\n\n\n<p>Auch <strong>ausgeleierte Rei\u00dfverschl\u00fcsse<\/strong> lassen sich mit etwas handwerklichem Geschick schnell und einfach wieder fixieren. Springt der Rei\u00dfverschluss beim Schlie\u00dfen oder \u00d6ffnen oft aus seiner F\u00fchrung, muss der Zipper ein wenig nachjustiert werden. Hierzu reicht es, wenn man ihn rechts und links ein wenig mit einer Kombizange zusammendr\u00fcckt. Dies sollte jedoch \u00e4u\u00dferst vorsichtig geschehen und bei Bedarf gegebenenfalls wiederholt werden. Dar\u00fcber hinaus ist auch der Austausch eines defekten Zippers m\u00f6glich. Bei eingerissenen Rei\u00dfverschl\u00fcssen sollte man jedoch definitiv einen Fachmann ans Werk lassen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-beschadigungen-durch-aussere-einflusse\">Besch\u00e4digungen durch \u00e4u\u00dfere Einfl\u00fcsse<\/h2>\n\n\n\n<p>Es ist schneller passiert, als man denkt. Einmal zu eng an der Dornenhecke oder dem scharfkantigen Fels vorbei, einmal am Lagerfeuer nicht auf den Funkenflug geachtet, einmal mit Pickel und Co. ausgerutscht und <strong>schon ist ein Loch oder Riss in der Jacke<\/strong>. Doch auch das muss <strong>noch nicht das Aus f\u00fcr das edle Kleidungsst\u00fcck<\/strong> sein und man kann die Hardshelljacke reparieren.<\/p>\n\n\n\n<p>Mit <strong>Flicken<\/strong>, <strong>Kleber<\/strong> und <strong>geeigneten Klebeb\u00e4ndern<\/strong>&nbsp;kann man kleineren Besch\u00e4digungen dieser Art einfach und effektiv selbst zu Leibe r\u00fccken. Diverse Hersteller bieten diesbez\u00fcglich Reparatursets an. Dabei ist es jedoch wichtig, dass man darauf achtet, dass das<strong> jeweilige Set auch f\u00fcr das Material der Jacke geeignet<\/strong> ist. Denn nicht jeder Flicken h\u00e4lt auf jedem Untergrund.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2021\/05\/Bild-21.jpg\"><img decoding=\"async\" src=\"https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2021\/05\/Bild-21.jpg\" alt=\"Pflegeanleitung Hardshell\" class=\"wp-image-24890\" style=\"object-fit:cover\"\/><\/a><figcaption class=\"wp-element-caption\">Das Reparaturset muss auf das Jackenmaterial abgestimmt sein<\/figcaption><\/figure>\n<\/div>\n\n\n<p>F\u00fcr eine saubere Reparatur ben\u00f6tigt man <strong>zwei Flicken<\/strong>, einen f\u00fcr <strong>au\u00dfen<\/strong>, den anderen f\u00fcr <strong>innen<\/strong>. Je nach Hersteller werden vorgefertigte oder anpassbare Flicken angeboten. Wichtig ist jedoch, dass der <strong>Flicken deutlich gr\u00f6\u00dfer als die besch\u00e4digte Stelle<\/strong> ist. Bei Rissen sollte er beidseitig circa einen Zentimeter l\u00e4nger sein. Bevor man mit dem Kleben beginnt, ist es auch hier wichtig, die besch\u00e4digte Stelle gr\u00fcndlich zu reinigen. Alkoholtupfer oder Spiritus k\u00f6nnen dabei sehr hilfreich sein. Danach k\u00f6nnen die Flicken von innen und von au\u00dfen auf die besch\u00e4digte Stelle geklebt werden. Auch hier sollte man darauf achten, dass keine Falten entstehen und der Flicken \u00fcberall sauber klebt.<\/p>\n\n\n\n<p>Tipp: Zahlreiche Hersteller bieten ihre <strong>Reparatursets in verschiedenen Farben<\/strong> an. Wer also beispielsweise eine rote Jacke reparieren m\u00f6chte, sollte daher vorab schauen, ob ein Hersteller das passende oder ein sehr \u00e4hnliches Rot im Angebot hat.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-reparatour\">ReparaTour<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2022\/12\/IMG_42771.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2022\/12\/IMG_42771.jpg\" alt=\"GearAid - Seam Grip - Nahtdichter und Universal Repair Kit sowie GearAid - Gore-Tex Repair Kit\" class=\"wp-image-60447\" style=\"object-fit:cover\" srcset=\"https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2022\/12\/IMG_42771.jpg 900w, https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2022\/12\/IMG_42771-300x200.jpg 300w, https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2022\/12\/IMG_42771-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><figcaption class=\"wp-element-caption\">GearAid &#8211; Seam Grip &#8211; Nahtdichter und Universal Repair Kit sowie GearAid &#8211; Gore-Tex Repair Kit<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Wer lange Touren in entlegenen Gebieten macht, sollte m\u00f6glichst gegen alles gewappnet sein. Das macht nat\u00fcrlich zuweilen das Gep\u00e4ck schwer. Dennoch ist es, je nach Vorhaben durchaus ratsam, ein kleines Flickenset mitzuf\u00fchren. Damit lassen sich n\u00e4mlich <strong>nicht nur Jacke, Hose und Co. reparieren, sondern im Zweifelsfall auch <a href=\"https:\/\/www.bergfreunde.de\/zelte\/\">Zelte<\/a> und <a href=\"https:\/\/www.bergfreunde.de\/isomatten\/\">Isomatten<\/a><\/strong>. Ebenso ist das allseits bekannte <a title=\"Der McNett - Seam Grip - Nahtdichter im Shop\" href=\"https:\/\/www.bergfreunde.de\/gearaid-seam-grip-nahtdichter\/\" target=\"_blank\" rel=\"noopener\">Seam Grip von GearAid<\/a>&nbsp;eine echte Allzweckwaffe. Dieser Kleber auf Urethanbasis klebt zahlreiche Materialien und dichtet sie gleichzeitig zuverl\u00e4ssig ab.<\/p>\n\n\n\n<p>Ist jedoch gerade kein geeignetes Reparaturmaterial zur Hand, k\u00f6nnen Hardshelljacken auch provisorisch <strong>mit Panzerband oder Fingertape geflickt<\/strong> werden. Hierdurch b\u00fc\u00dft die Jacke zwar zeitweilig ein wenig an Funktionalit\u00e4t ein, gerade bei Schnitten und Rissen kann man so jedoch <strong>verhindern, dass diese mit der Zeit gr\u00f6\u00dfer werden<\/strong>. Diese Methode ist allerdings wirklich nur f\u00fcr den absoluten Notfall beim Hardshelljacken reparieren gedacht, da der Kleber des jeweiligen Bandes mit der Zeit sehr stark an der Jacke klebt und nur noch schlecht zu entfernen ist.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-professionelle-reparatur-der-hardshelljacke\">Professionelle Reparatur der Hardshelljacke<\/h2>\n\n\n\n<p>Manchmal kommt es jedoch hart auf hart und selbst MacGyver w\u00fcrde nur noch ein langes Gesicht machen. In diesem Fall sollte man sich auf jeden Fall zuerst an den Shop wenden, wo man die Jacke erworben hat. Dort erf\u00e4hrt man, welche Vorgehensweise die jeweiligen Hersteller vorgeben und was dabei zu beachten ist. Oft kann der H\u00e4ndler auch an einen Reparaturservice verweisen, der die Jacke kostenpflichtig repariert. Ob gro\u00dfe Reparaturzentren wie die von Gore-Tex und Norr\u00f6na oder freie Anbieter wie das Outdoor Service Team in Berlin, es gibt zahlreiche Reparaturdienste, die sich selbst schwerwiegendster Besch\u00e4digungen annehmen. Handelt es sich bei dem vorliegenden Schaden jedoch nicht um einen Garantiefall, empfiehlt es sich, <strong>vorab die Kosten und die gesch\u00e4tzte Bearbeitungsdauer<\/strong> zu erfragen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-fazit-hardshelljacken-reparieren\">Fazit Hardshelljacken reparieren<\/h2>\n\n\n\n<p>Eine Besch\u00e4digung muss nicht gleich das Aus f\u00fcr eine Jacke bedeuten. Wer sich ein wenig Gedanken \u00fcber <a title=\"Reparatursets und Pflegeartikel im Shop!\" href=\"https:\/\/www.bergfreunde.de\/ausruestungspflege\/\" target=\"_blank\" rel=\"noopener\">das richtige Reparaturmaterial<\/a> macht, und die Packungshinweise des Herstellers beachtet, hat beste Chancen, weiterhin viel Spa\u00df mit seiner Jacke zu haben. Mit etwas Gl\u00fcck f\u00e4llt die Flickerei sp\u00e4ter nicht einmal gro\u00dfartig auf. Wer es sich nicht zutraut, die Hardshelljacke zu reparieren, der sollte sich auf jeden Fall an den H\u00e4ndler wenden.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.bergfreunde.de\/regenjacken\/\">Eine gro\u00dfe Auswahl an Hardshelljacken findest du hier &gt;&gt;<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Fr\u00fcher war alles einfacher. Loch im Wollpullover: Mutti stopft das. Hose zerrissen: Zuerst gab es \u00c4rger mit dem Vater, danach einen Flicken von der Mutter. Die Zeiten der Strickpullover und Kniebundhosen sind aber in den Bergen schon lang vorbei. Heute kommen Funktionstextilien aller Art zum Einsatz und teilweise auch an ihre Grenzen. Muss aber ein [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":60454,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[107],"tags":[25,145,23,24],"post_folder":[],"class_list":["post-17322","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pflege-reparatur","tag-bergsteigen","tag-bike","tag-klettern-bouldern","tag-wandern-trekking"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gore-Tex Jacken richtig flicken &amp; reparieren - Anleitung | Bergfreunde<\/title>\n<meta name=\"description\" content=\"Einmal nicht aufgepasst und schon ist die geliebte Hardshelljacke besch\u00e4digt. In diesem Beitrag lernst du deine Hardshelljacke zu reparieren!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bergfreunde.de\/blog\/pflegeanleitung-hardshelljacken\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hardshelljacken reparieren \u2013 Erste Hilfe f\u00fcr die Jacke\" \/>\n<meta property=\"og:description\" content=\"Einmal nicht aufgepasst und schon ist die geliebte Hardshelljacke besch\u00e4digt. In diesem Beitrag lernst du deine Hardshelljacke zu reparieren!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bergfreunde.de\/blog\/pflegeanleitung-hardshelljacken\/\" \/>\n<meta property=\"og:site_name\" content=\"Bergfreunde\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bergfreunde\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-01T11:03:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-08T08:33:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2015\/09\/pexels-gabriela-palai-404960.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"961\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lisa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lisa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog\\\/pflegeanleitung-hardshelljacken\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog\\\/pflegeanleitung-hardshelljacken\\\/\"},\"author\":{\"name\":\"Lisa\",\"@id\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog#\\\/schema\\\/person\\\/0be5fb2399f7af8673f0e675d4964f8d\"},\"headline\":\"Hardshelljacken reparieren \u2013 Erste Hilfe f\u00fcr die Jacke\",\"datePublished\":\"2022-09-01T11:03:00+00:00\",\"dateModified\":\"2025-08-08T08:33:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog\\\/pflegeanleitung-hardshelljacken\\\/\"},\"wordCount\":1217,\"commentCount\":29,\"publisher\":{\"@id\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog\\\/pflegeanleitung-hardshelljacken\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/pexels-gabriela-palai-404960.jpg\",\"keywords\":[\"Bergsteigen &amp; Hochtouren\",\"Bike\",\"Klettern &amp; Bouldern\",\"Wandern &amp; Trekking\"],\"articleSection\":[\"Pflege &amp; Reparatur\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.bergfreunde.de\\\/blog\\\/pflegeanleitung-hardshelljacken\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog\\\/pflegeanleitung-hardshelljacken\\\/\",\"url\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog\\\/pflegeanleitung-hardshelljacken\\\/\",\"name\":\"Gore-Tex Jacken richtig flicken & reparieren - Anleitung | Bergfreunde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog\\\/pflegeanleitung-hardshelljacken\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog\\\/pflegeanleitung-hardshelljacken\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/pexels-gabriela-palai-404960.jpg\",\"datePublished\":\"2022-09-01T11:03:00+00:00\",\"dateModified\":\"2025-08-08T08:33:13+00:00\",\"description\":\"Einmal nicht aufgepasst und schon ist die geliebte Hardshelljacke besch\u00e4digt. In diesem Beitrag lernst du deine Hardshelljacke zu reparieren!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog\\\/pflegeanleitung-hardshelljacken\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bergfreunde.de\\\/blog\\\/pflegeanleitung-hardshelljacken\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog\\\/pflegeanleitung-hardshelljacken\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/pexels-gabriela-palai-404960.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/pexels-gabriela-palai-404960.jpg\",\"width\":1440,\"height\":961},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog\\\/pflegeanleitung-hardshelljacken\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Know-How\",\"item\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog\\\/category\\\/know-how\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pflege &amp; Reparatur\",\"item\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog\\\/category\\\/know-how\\\/pflege-reparatur\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Hardshelljacken reparieren \u2013 Erste Hilfe f\u00fcr die Jacke\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog#website\",\"url\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog\",\"name\":\"Bergfreunde\",\"description\":\"Blog\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog#organization\",\"name\":\"Bergfreunde\",\"url\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Bergfreunde_DE_rgb.svg\",\"contentUrl\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Bergfreunde_DE_rgb.svg\",\"width\":360,\"height\":123,\"caption\":\"Bergfreunde\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bergfreunde\",\"https:\\\/\\\/www.instagram.com\\\/bergfreundede\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog#\\\/schema\\\/person\\\/0be5fb2399f7af8673f0e675d4964f8d\",\"name\":\"Lisa\",\"url\":\"https:\\\/\\\/www.bergfreunde.de\\\/blog\\\/about\\\/lisa-kopas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gore-Tex Jacken richtig flicken & reparieren - Anleitung | Bergfreunde","description":"Einmal nicht aufgepasst und schon ist die geliebte Hardshelljacke besch\u00e4digt. In diesem Beitrag lernst du deine Hardshelljacke zu reparieren!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bergfreunde.de\/blog\/pflegeanleitung-hardshelljacken\/","og_locale":"de_DE","og_type":"article","og_title":"Hardshelljacken reparieren \u2013 Erste Hilfe f\u00fcr die Jacke","og_description":"Einmal nicht aufgepasst und schon ist die geliebte Hardshelljacke besch\u00e4digt. In diesem Beitrag lernst du deine Hardshelljacke zu reparieren!","og_url":"https:\/\/www.bergfreunde.de\/blog\/pflegeanleitung-hardshelljacken\/","og_site_name":"Bergfreunde","article_publisher":"https:\/\/www.facebook.com\/bergfreunde","article_published_time":"2022-09-01T11:03:00+00:00","article_modified_time":"2025-08-08T08:33:13+00:00","og_image":[{"width":1440,"height":961,"url":"https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2015\/09\/pexels-gabriela-palai-404960.jpg","type":"image\/jpeg"}],"author":"Lisa","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Lisa","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.bergfreunde.de\/blog\/pflegeanleitung-hardshelljacken\/#article","isPartOf":{"@id":"https:\/\/www.bergfreunde.de\/blog\/pflegeanleitung-hardshelljacken\/"},"author":{"name":"Lisa","@id":"https:\/\/www.bergfreunde.de\/blog#\/schema\/person\/0be5fb2399f7af8673f0e675d4964f8d"},"headline":"Hardshelljacken reparieren \u2013 Erste Hilfe f\u00fcr die Jacke","datePublished":"2022-09-01T11:03:00+00:00","dateModified":"2025-08-08T08:33:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bergfreunde.de\/blog\/pflegeanleitung-hardshelljacken\/"},"wordCount":1217,"commentCount":29,"publisher":{"@id":"https:\/\/www.bergfreunde.de\/blog#organization"},"image":{"@id":"https:\/\/www.bergfreunde.de\/blog\/pflegeanleitung-hardshelljacken\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2015\/09\/pexels-gabriela-palai-404960.jpg","keywords":["Bergsteigen &amp; Hochtouren","Bike","Klettern &amp; Bouldern","Wandern &amp; Trekking"],"articleSection":["Pflege &amp; Reparatur"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.bergfreunde.de\/blog\/pflegeanleitung-hardshelljacken\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.bergfreunde.de\/blog\/pflegeanleitung-hardshelljacken\/","url":"https:\/\/www.bergfreunde.de\/blog\/pflegeanleitung-hardshelljacken\/","name":"Gore-Tex Jacken richtig flicken & reparieren - Anleitung | Bergfreunde","isPartOf":{"@id":"https:\/\/www.bergfreunde.de\/blog#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bergfreunde.de\/blog\/pflegeanleitung-hardshelljacken\/#primaryimage"},"image":{"@id":"https:\/\/www.bergfreunde.de\/blog\/pflegeanleitung-hardshelljacken\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2015\/09\/pexels-gabriela-palai-404960.jpg","datePublished":"2022-09-01T11:03:00+00:00","dateModified":"2025-08-08T08:33:13+00:00","description":"Einmal nicht aufgepasst und schon ist die geliebte Hardshelljacke besch\u00e4digt. In diesem Beitrag lernst du deine Hardshelljacke zu reparieren!","breadcrumb":{"@id":"https:\/\/www.bergfreunde.de\/blog\/pflegeanleitung-hardshelljacken\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bergfreunde.de\/blog\/pflegeanleitung-hardshelljacken\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.bergfreunde.de\/blog\/pflegeanleitung-hardshelljacken\/#primaryimage","url":"https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2015\/09\/pexels-gabriela-palai-404960.jpg","contentUrl":"https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2015\/09\/pexels-gabriela-palai-404960.jpg","width":1440,"height":961},{"@type":"BreadcrumbList","@id":"https:\/\/www.bergfreunde.de\/blog\/pflegeanleitung-hardshelljacken\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.bergfreunde.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Know-How","item":"https:\/\/www.bergfreunde.de\/blog\/category\/know-how\/"},{"@type":"ListItem","position":3,"name":"Pflege &amp; Reparatur","item":"https:\/\/www.bergfreunde.de\/blog\/category\/know-how\/pflege-reparatur\/"},{"@type":"ListItem","position":4,"name":"Hardshelljacken reparieren \u2013 Erste Hilfe f\u00fcr die Jacke"}]},{"@type":"WebSite","@id":"https:\/\/www.bergfreunde.de\/blog#website","url":"https:\/\/www.bergfreunde.de\/blog","name":"Bergfreunde","description":"Blog","publisher":{"@id":"https:\/\/www.bergfreunde.de\/blog#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bergfreunde.de\/blog?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.bergfreunde.de\/blog#organization","name":"Bergfreunde","url":"https:\/\/www.bergfreunde.de\/blog","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.bergfreunde.de\/blog#\/schema\/logo\/image\/","url":"https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2023\/12\/Bergfreunde_DE_rgb.svg","contentUrl":"https:\/\/www.bergfreunde.de\/blog\/wp-content\/uploads\/2023\/12\/Bergfreunde_DE_rgb.svg","width":360,"height":123,"caption":"Bergfreunde"},"image":{"@id":"https:\/\/www.bergfreunde.de\/blog#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bergfreunde","https:\/\/www.instagram.com\/bergfreundede\/"]},{"@type":"Person","@id":"https:\/\/www.bergfreunde.de\/blog#\/schema\/person\/0be5fb2399f7af8673f0e675d4964f8d","name":"Lisa","url":"https:\/\/www.bergfreunde.de\/blog\/about\/lisa-kopas\/"}]}},"_links":{"self":[{"href":"https:\/\/www.bergfreunde.de\/blog\/wp-json\/wp\/v2\/posts\/17322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bergfreunde.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bergfreunde.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bergfreunde.de\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bergfreunde.de\/blog\/wp-json\/wp\/v2\/comments?post=17322"}],"version-history":[{"count":3,"href":"https:\/\/www.bergfreunde.de\/blog\/wp-json\/wp\/v2\/posts\/17322\/revisions"}],"predecessor-version":[{"id":125008,"href":"https:\/\/www.bergfreunde.de\/blog\/wp-json\/wp\/v2\/posts\/17322\/revisions\/125008"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bergfreunde.de\/blog\/wp-json\/wp\/v2\/media\/60454"}],"wp:attachment":[{"href":"https:\/\/www.bergfreunde.de\/blog\/wp-json\/wp\/v2\/media?parent=17322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bergfreunde.de\/blog\/wp-json\/wp\/v2\/categories?post=17322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bergfreunde.de\/blog\/wp-json\/wp\/v2\/tags?post=17322"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.bergfreunde.de\/blog\/wp-json\/wp\/v2\/post_folder?post=17322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}